{"id":399354,"date":"2025-07-31T09:32:39","date_gmt":"2025-07-31T09:32:39","guid":{"rendered":"https:\/\/belux.edmo.eu\/?p=399354"},"modified":"2025-07-31T14:04:56","modified_gmt":"2025-07-31T14:04:56","slug":"attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia","status":"publish","type":"post","link":"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/","title":{"rendered":"Attention, ces images d&rsquo;\u00c9gyptiens lan\u00e7ant des bouteilles remplies de vivres vers Gaza ont \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9es par IA"},"content":{"rendered":"<p>D\u00e9but mars 2025, Isra\u00ebl a impos\u00e9 \u00e0 Gaza un blocus qui a entra\u00een\u00e9 de tr\u00e8s graves p\u00e9nuries alimentaires, selon l&rsquo;ONU et des ONG, parmi ses plus de deux millions d&rsquo;habitants. Le terme de \u00ab\u00a0famine\u00a0\u00bb a officiellement \u00e9t\u00e9 act\u00e9 le 29 juillet par l&rsquo;IPC, organisation sp\u00e9cialis\u00e9e soutenue par l&rsquo;ONU. Dans ce contexte, des images sont diffus\u00e9es par des internautes affirmant qu&rsquo;elles montrent des \u00c9gyptiens jetant \u00e0 la mer des bouteilles remplies de riz, de farine ou de lait en direction de Gaza, en signe de solidarit\u00e9. Mais si cette initiative a bien exist\u00e9, les photos en question ne sont pas authentiques et ont \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9es par intelligence artificielle.<\/p>\n<p>Pour la premi\u00e8re fois depuis des mois,<a href=\"https:\/\/www.lexpress.fr\/monde\/israel-annonce-de-premieres-livraisons-daide-humanitaire-a-gaza-4UGZNAU2CVFDDGPX7YTQ7QYZK4\/\" target=\"_blank\" rel=\"evidence nofollow noopener\" shape=\"rect\"> des camions charg\u00e9s d&rsquo;aide internationale <\/a>venus d&rsquo;Egypte ont travers\u00e9 le 27juillet le point de passage de Rafah, qui m\u00e8ne vers le sud du territoire palestinien assi\u00e9g\u00e9, apr\u00e8s l&rsquo;annonce par Isra\u00ebl d&rsquo;une pause limit\u00e9e des combats \u00e0 des fins humanitaires (archive:\u00a0<a href=\"https:\/\/perma.cc\/BY3P-NVNB\" target=\"_blank\" rel=\"evidence frozen nofollow noopener\" shape=\"rect\">ici<\/a>).<\/p>\n<p>Les largages de vivres avaient aussi repris au-dessus du territoire, assi\u00e9g\u00e9 par Isra\u00ebl depuis le d\u00e9but de la guerre contre le Hamas il y a pr\u00e8s de 22 mois, suscitant l&rsquo;espoir de nombreux Palestiniens qui guettaient les parachutes dans le ciel.<\/p>\n<p data-end=\"1836\" data-start=\"1697\">Dans la foul\u00e9e, de nombreuses images montrant des bouteilles remplies de ce qui ressemble \u00e0 du riz ou de la farine flottant sur la mer ont commenc\u00e9 \u00e0 circuler en ligne.<\/p>\n<p>\u00ab\u00a0<em><span style=\"list-style-type: none;\">Des jeunes \u00e9gyptiens d\u00e9sesp\u00e9r\u00e9s d&rsquo;impuissance et \u00e9c\u0153ur\u00e9s par l&rsquo;indiff\u00e9rence du r\u00e9gime \u00e9gyptien au sort des palestiniens affam\u00e9s par ses ma\u00eetres isra\u00e9liens et \u00e9tats-uniens<\/span><\/em><span style=\"list-style-type: none;\"><em> jette des bouteilles \u00e0 la mer remplies de lait pour b\u00e9b\u00e9, de farine et de riz dans l&rsquo;espoir qu&rsquo;elles arrivent \u00e0 Gaza<\/em>\u00ab\u00a0, \u00e9crit une <a href=\"https:\/\/perma.cc\/U7TE-EKGQ\" target=\"_blank\" rel=\"appearance frozen nofollow noopener\" shape=\"rect\">internaute <\/a>sur X.<\/span><\/p>\n<p>Sa publication a \u00e9t\u00e9 vue plus plus de 52.000 fois de fois et partag\u00e9e par pr\u00e8s de 670 personnes.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"g2picture\">\n<figure><img src=\"https:\/\/belux-edmo.s3-accelerate.amazonaws.com\/wp-content\/uploads\/2025\/07\/a357112c2170289283c51e2b80621c12f4ab0a42-ipad.jpg\" \/><figcaption>Capture d&rsquo;\u00e9cran r\u00e9alis\u00e9e sur X le 29\/07\/2025. Croix rouge ajout\u00e9e par l&rsquo;AFP.<\/figcaption><\/figure>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Ces images virales ont tromp\u00e9 de nombreux internautes. Elles ont \u00e9t\u00e9 partag\u00e9es en plusieurs langues parmi lesquelles <a href=\"https:\/\/perma.cc\/3ZCR-8PCH\" target=\"_blank\" rel=\"appearance frozen nofollow noopener\" shape=\"rect\">l&rsquo;anglais<\/a>, <a href=\"https:\/\/perma.cc\/8ZAB-QUVK\" target=\"_blank\" rel=\"appearance frozen nofollow noopener\" shape=\"rect\">l&rsquo;italien<\/a>, le <a href=\"https:\/\/archive.is\/rHilg\" target=\"_blank\" rel=\"appearance frozen nofollow noopener\" shape=\"rect\">bengali<\/a>, et <a href=\"https:\/\/archive.is\/5YfzG\" target=\"_blank\" rel=\"appearance frozen nofollow noopener\" shape=\"rect\">l&rsquo;arabe\u00a0<\/a>et sur diff\u00e9rentes plateformes, telles que Facebook, <a href=\"https:\/\/www.instagram.com\/p\/DMhwJqGoeOf\/?img_index=1\" target=\"_blank\" rel=\"appearance frozen nofollow noopener\" shape=\"rect\">Instagram<\/a> et <a href=\"https:\/\/perma.cc\/MNB5-P57E\" target=\"_blank\" rel=\"appearance frozen nofollow noopener\" shape=\"rect\">TikTok<\/a>. Elles ont \u00e9t\u00e9 relay\u00e9es sur de nombreux sites internet \u00e9galement (<a href=\"https:\/\/perma.cc\/7FKU-VZLY\" target=\"_blank\" rel=\"appearance frozen nofollow noopener\" shape=\"rect\">1<\/a>, <a href=\"https:\/\/perma.cc\/PV8V-ERVS\" target=\"_blank\" rel=\"appearance frozen nofollow noopener\" shape=\"rect\">2<\/a>, <a href=\"https:\/\/perma.cc\/BN96-FXAL\" target=\"_blank\" rel=\"appearance frozen nofollow noopener\" shape=\"rect\">3<\/a>, <a href=\"https:\/\/perma.cc\/6M5L-UBS5\" target=\"_blank\" rel=\"appearance frozen nofollow noopener\" shape=\"rect\">4<\/a>).<\/p>\n<p><em>\u00ab\u00a0Terrible d&rsquo;en arriver l\u00e0 !\u00a0\u00bb<\/em>, <em>\u00ab\u00a0bravo \u00e0 eux!\u00a0\u00bb,<\/em> peut-on par exemple lire en commentaires.<\/p>\n<p data-end=\"1797\" data-start=\"1701\">Mais ces images ne sont pas authentiques : elles ont \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9es par intelligence artificielle (IA).<\/p>\n<p><b><strong data-olk-copy-source=\"MailCompose\">Plusieurs anomalies<\/strong><\/b><\/p>\n<p>Une analyse effectu\u00e9e \u00e0 l&rsquo;aide de l&rsquo;outil de d\u00e9tection <a href=\"https:\/\/thehive.ai\/\" target=\"_blank\" rel=\"evidence nofollow noopener\" shape=\"rect\">Hive<\/a>, sp\u00e9cialis\u00e9 dans la v\u00e9rification d&rsquo;images, a conclu \u00e0 99,9 % de probabilit\u00e9 que ces visuels aient \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9s par intelligence artificielle.<\/p>\n<p>En effet, un examen attentif r\u00e9v\u00e8le en effet plusieurs incoh\u00e9rences visuelles caract\u00e9ristiques des images cr\u00e9\u00e9es par IA :<\/p>\n<ul>\n<li>Sur l&rsquo;un des clich\u00e9s, le pouce au premier plan appara\u00eet d\u00e9form\u00e9.<\/li>\n<li>Les bouteilles, pourtant remplies, flottent de mani\u00e8re improbable, d\u00e9fiant les lois de la physique.<\/li>\n<li>Les individus sont tous positionn\u00e9s de la m\u00eame fa\u00e7on et dans la m\u00eame direction, de fa\u00e7on peu naturelle.<\/li>\n<\/ul>\n<div class=\"g2picture\">\n<figure><img src=\"https:\/\/belux-edmo.s3-accelerate.amazonaws.com\/wp-content\/uploads\/2025\/07\/54ef802da1b2043f71eb6c45ae6c1a008e0ef026-ipad.jpg\" \/><figcaption>Capture d&rsquo;\u00e9cran r\u00e9alis\u00e9e sur X le 28\/07\/2025 (\u00e0 gauche) et du r\u00e9sultat de l&rsquo;outil Hive (\u00e0 droite). Encadr\u00e9s color\u00e9s ajout\u00e9s par l&rsquo;AFP.<\/figcaption><\/figure>\n<\/div>\n<p>Sur une autre photo, une bouteille porte une inscription en arabe : <em>\u00ab\u00a0Le peuple \u00e9gyptien pour Gaza\u00a0\u00bb<\/em>, et flotte verticalement \u00e0 la surface de l&rsquo;eau.<\/p>\n<div class=\"g2picture\">\n<figure><img src=\"https:\/\/belux-edmo.s3-accelerate.amazonaws.com\/wp-content\/uploads\/2025\/07\/6d5fb870545d9ef99cef0f06fd279ffc838bbdf9-ipad.jpg\" \/><figcaption>Capture d&rsquo;\u00e9cran r\u00e9alis\u00e9e sur X le 29\/07\/2025. Croix rouge ajout\u00e9e par l&rsquo;AFP.<\/figcaption><\/figure>\n<\/div>\n<p>Une <a href=\"https:\/\/www.youtube.com\/watch?v=w6tpIBHhZLw\" target=\"_blank\" rel=\"evidence frozen nofollow noopener\" shape=\"rect\">recherche d&rsquo;images invers\u00e9es<\/a> a permis de retrouver des images similaires, cens\u00e9es illustrer la m\u00eame sc\u00e8ne (<a href=\"https:\/\/perma.cc\/7FKU-VZLY\" target=\"_blank\" rel=\"appearance frozen nofollow noopener\" shape=\"rect\">1<\/a>, <a href=\"https:\/\/perma.cc\/PV8V-ERVS\" target=\"_blank\" rel=\"appearance frozen nofollow noopener\" shape=\"rect\">2<\/a>).<\/p>\n<p>L\u00e0 encore, plusieurs anomalies apparaissent : des visages d\u00e9form\u00e9s, un bras anormalement long, des doigts disproportionn\u00e9s, et des bouteilles flottant dans les airs. De plus, en bas \u00e0 droite de l&rsquo;image, l&rsquo;inscription \u00ab\u00a0Grok\u00a0\u00bb appara\u00eet.<\/p>\n<p>Il s&rsquo;agit du logiciel d&rsquo;IA de X, qui permet aux utilisateurs de cr\u00e9er des images gratuitement \u00e0 partir de simples descriptions textuelles. N\u00e9anmoins, les contenus produits pr\u00e9sentent souvent les imperfections caract\u00e9ristiques des rendus IA : postures fig\u00e9es, duplications d&rsquo;\u00e9l\u00e9ments, erreurs anatomiques ou perspectives incoh\u00e9rentes.<\/p>\n<p>Plusieurs \u00e9l\u00e9ments peuvent permettre de d\u00e9terminer si un contenu a \u00e9t\u00e9 cr\u00e9\u00e9 par IA, comme nous l&rsquo;expliquions dans\u00a0<a href=\"https:\/\/factuel.afp.com\/doc.afp.com.36NN9A7\" target=\"_blank\" rel=\"nofollow noopener evidence\" shape=\"rect\">cet article<\/a>.<\/p>\n<div class=\"g2picture\">\n<figure><img src=\"https:\/\/belux-edmo.s3-accelerate.amazonaws.com\/wp-content\/uploads\/2025\/07\/968c0e994b2b527514907fc8a15756ae687a7dcb-ipad.jpg\" \/><figcaption>Capture d&rsquo;\u00e9cran r\u00e9alis\u00e9e sur le site &lsquo;Infolibertaire&rsquo; le 28\/07\/2025. Encadr\u00e9s color\u00e9s ajout\u00e9s par l&rsquo;AFP<\/figcaption><\/figure>\n<\/div>\n<p><b>Une aide humanitaire toujours tr\u00e8s limit\u00e9e\u00a0<\/b><\/p>\n<p>Si les images qui circulent en masse sur les r\u00e9seaux sociaux ne sont pas authentiques, elles s&rsquo;inspirent d&rsquo;une initiative bien r\u00e9elle.<\/p>\n<p>Le 23 juillet, un homme a \u00e9t\u00e9 film\u00e9 en train de jeter des bouteilles en plastique \u00e0 la mer.<\/p>\n<p><em>\u00ab\u00a0Pardonnez-nous nos fr\u00e8res ! Pardonnez-nous. Nous sommes incapables de faire quelque chose pour vous !\u00a0\u00bb,<\/em> peut-on l&rsquo;entendre dire dans une vid\u00e9o diffus\u00e9e par <a href=\"https:\/\/www.youtube.com\/shorts\/8KNrmQ9HTZ8\" target=\"_blank\" rel=\"evidence nofollow noopener\" shape=\"rect\">Middle East Eye<\/a>, le m\u00e9dia anglophone consacr\u00e9 \u00e0 l&rsquo;actualit\u00e9 du Moyen-Orient et de l&rsquo;Afrique du Nord (archive:\u00a0<a href=\"https:\/\/perma.cc\/RXJ5-JX48\" target=\"_blank\" rel=\"evidence frozen nofollow noopener\" shape=\"rect\">ici<\/a>).<\/p>\n<p>Ce geste symbolique et \u00ab\u00a0<em>d\u00e9sesp\u00e9r\u00e9<\/em>\u00a0\u00bb s&rsquo;inscrit dans une initiative intitul\u00e9e :\u00a0 \u00ab\u00a0<em>De la mer \u00e0 la mer \u2212 une bouteille d&rsquo;espoir pour Gaza\u00a0\u00bb<\/em>, lanc\u00e9e par \u00ab\u00a0<em>des citoyens \u00e9gyptiens horrifi\u00e9s par les images de la famine<\/em>\u00a0\u00bb en cours dans l&rsquo;enclave palestinienne, explique le <a href=\"https:\/\/www.newarab.com\/news\/egyptians-symbolically-send-food-gaza-bottles-sea\" target=\"_blank\" rel=\"evidence nofollow noopener\" shape=\"rect\">m\u00e9dia<\/a> anglophone The New Arab (archive:\u00a0<a href=\"https:\/\/perma.cc\/Z93T-EVL2\" target=\"_blank\" rel=\"evidence frozen nofollow noopener\" shape=\"rect\">ici<\/a>).<\/p>\n<p>Ces derniers remplissent des bouteilles d&rsquo;un ou de deux litres de riz, lait ou c\u00e9r\u00e9ales avant de les jeter dans la M\u00e9diterran\u00e9e. Ils ont aussi appel\u00e9 les citoyens d&rsquo;autres pays comme la Libye, la Tunisie, l&rsquo;Alg\u00e9rie et le Maroc, \u00e0 se joindre \u00e0 l&rsquo;initiative.<\/p>\n<div class=\"g2web\" style=\"text-align: center;\">\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/DMinfCbIeJn\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<div style=\"padding: 16px;\">\n<p>&nbsp;<\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Voir cette publication sur Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/reel\/DMinfCbIeJn\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener\" shape=\"rect\">Une publication partag\u00e9e par Middle East Eye (@middleeasteye)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async=\"\" src=\"\/\/www.instagram.com\/embed.js\" type=\"text\/javascript\" xml:space=\"preserve\"><\/script><\/p>\n<\/div>\n<p>Isra\u00ebl a annonc\u00e9 le 28 juillet que l&rsquo;aide achemin\u00e9e par 120 camions avait \u00e9t\u00e9 \u00ab\u00a0<a href=\"https:\/\/www.lemonde.fr\/international\/live\/2025\/07\/29\/en-direct-gaza-le-hamas-doit-rendre-son-controle-sur-l-enclave-plaide-le-premier-ministre-palestinien-mohammad-mustafa_6624772_3210.html\" target=\"_blank\" rel=\"evidence nofollow noopener\" shape=\"rect\">distribu\u00e9e<\/a>\u00a0\u00bb dans le territoire par l&rsquo;ONU et des organisations internationales, apr\u00e8s l&rsquo;annonce dimanche d&rsquo;une pause quotidienne des combats dans plusieurs secteurs (archive: <a href=\"https:\/\/perma.cc\/383D-Q4GK\" target=\"_blank\" rel=\"evidence frozen nofollow noopener\" shape=\"rect\">ici<\/a>).<\/p>\n<p>Isra\u00ebl, qui contr\u00f4le tous les acc\u00e8s \u00e0 Gaza, nie tout blocage de l&rsquo;aide, accusant le mouvement islamiste palestinien Hamas de piller les cargaisons et les organisations humanitaires de ne pas les distribuer.<\/p>\n<p>Mais ces organisations affirment qu&rsquo;Isra\u00ebl impose des restrictions excessives qui les emp\u00eachent de travailler.<\/p>\n<p>L&rsquo;IPC, organisme international de surveillance de la faim soutenu par l&rsquo;ONU, <a href=\"https:\/\/www.france24.com\/fr\/info-en-continu\/20250729-un-organisme-soutenu-par-l-onu-%C3%A9voque-le-pire-sc%C3%A9nario-de-famine-%C3%A0-gaza\" target=\"_blank\" rel=\"evidence nofollow noopener\" shape=\"rect\">a affirm\u00e9 le 29 juillet<\/a> que le \u00ab\u00a0<em>pire sc\u00e9nario de famine est en cours \u00e0 Gaza<\/em>\u00ab\u00a0, o\u00f9 Isra\u00ebl a autoris\u00e9 l&rsquo;entr\u00e9e de nouveaux camions d&rsquo;aides humanitaires jug\u00e9es \u00e0 ce stade insuffisantes par les agences internationales (lien archiv\u00e9 <a href=\"https:\/\/web.archive.org\/web\/20250729091750\/https:\/\/www.france24.com\/fr\/info-en-continu\/20250729-un-organisme-soutenu-par-l-onu-%C3%A9voque-le-pire-sc%C3%A9nario-de-famine-%C3%A0-gaza\" target=\"_blank\" rel=\"evidence frozen nofollow noopener\" shape=\"rect\">ici<\/a>).<\/p>\n<p>L&rsquo;agence de l&rsquo;ONU pour les r\u00e9fugi\u00e9s palestiniens, l&rsquo;Unrwa, a <a href=\"https:\/\/www.lapresse.ca\/international\/moyen-orient\/2025-07-28\/bande-de-gaza\/les-etats-unis-vont-etablir-des-centres-de-distribution-alimentaire.php\" target=\"_blank\" rel=\"evidence nofollow noopener\" shape=\"rect\">averti <\/a>qu&rsquo;il fallait au moins 500 \u00e0 600 camions de nourriture, de m\u00e9dicaments et de produits d&rsquo;hygi\u00e8ne chaque jour pour subvenir aux besoins de la population de Gaza (archive: <a href=\"https:\/\/perma.cc\/U5T5-S48E\" target=\"_blank\" rel=\"evidence frozen nofollow noopener\" shape=\"rect\">ici<\/a>).<\/p>\n<p>La guerre a \u00e9t\u00e9 d\u00e9clench\u00e9e par une attaque sans pr\u00e9c\u00e9dent men\u00e9e par le Hamas en Isra\u00ebl le 7 octobre 2023, qui a <a href=\"https:\/\/www.lopinion.fr\/international\/gaza-un-organisme-soutenu-par-lonu-evoque-le-pire-scenario-de-famine\" target=\"_blank\" rel=\"evidence nofollow noopener\" shape=\"rect\">entra\u00een\u00e9 <\/a>du c\u00f4t\u00e9 isra\u00e9lien la mort de 1.219 personnes, en majorit\u00e9 des civils, selon un d\u00e9compte de l&rsquo;AFP r\u00e9alis\u00e9 \u00e0 partir de donn\u00e9es officielles (archive: <a href=\"https:\/\/perma.cc\/VAK7-73SH\" target=\"_blank\" rel=\"evidence frozen nofollow noopener\" shape=\"rect\">ici<\/a>).<\/p>\n<p>En riposte, Isra\u00ebl a lanc\u00e9 une offensive qui a fait au moins pr\u00e8s de 60.000 morts \u00e0 Gaza, en majorit\u00e9 des civils, selon des donn\u00e9es du minist\u00e8re de la Sant\u00e9 du Hamas, jug\u00e9es fiables par l&rsquo;ONU.<\/p>\n<p>Au moment o\u00f9 la pression internationale sur Isra\u00ebl s&rsquo;intensifie pour mettre un terme \u00e0 la guerre, l&rsquo;ONU, pouss\u00e9e par la France et l&rsquo;Arabie saoudite, se penche \u00e0 partir du 28 juillet\u00a0sur l&rsquo;avenir menac\u00e9 de la solution \u00e0 deux Etats, isra\u00e9lien et palestinien.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9but mars 2025, Isra\u00ebl a impos\u00e9 \u00e0 Gaza un blocus qui a entra\u00een\u00e9 de tr\u00e8s graves p\u00e9nuries alimentaires, selon l&rsquo;ONU et des ONG, parmi ses plus de deux millions d&rsquo;habitants. Le terme de \u00ab\u00a0famine\u00a0\u00bb a officiellement \u00e9t\u00e9 act\u00e9 le 29 juillet par l&rsquo;IPC, organisation sp\u00e9cialis\u00e9e soutenue par l&rsquo;ONU. Dans ce contexte, des images sont diffus\u00e9es par des internautes affirmant qu&rsquo;elles montrent des \u00c9gyptiens jetant \u00e0 la mer des bouteilles remplies de riz, de farine ou de lait en direction de Gaza, en signe de solidarit\u00e9. Mais si cette initiative a bien exist\u00e9, les photos en question ne sont pas authentiques et ont \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9es par intelligence artificielle.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":399329,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[452,125,403,132,138,389],"tags":[],"class_list":["post-399354","post","type-post","status-publish","format-standard","has-post-thumbnail","category-editors-choice-fr","category-fact-check-fr","category-moyen-orient","category-politique","category-societe","category-technologie-fact-check-fr-2"],"acf":{"show_metatags":true,"id":"http:\/\/doc.afp.com\/683V363","authors":"Dounia MAHIEDDINE \/ AFP France","organization":"AFP","featured_image_copyright":"","text_copyright":"\u00a9 AGENCE FRANCE-PRESSE | 2024 | Tous droits r\u00e9serv\u00e9s. L\u2019acc\u00e8s aux contenus de l'AFP publi\u00e9s sur ce site et, le cas \u00e9ch\u00e9ant, leur utilisation sont soumis aux conditions g\u00e9n\u00e9rales d'utilisation disponibles sur <a href='https:\/\/www.afp.com\/fr\/cgu' target='_blank'>CGU<\/a>. Par cons\u00e9quent, en acc\u00e9dant aux contenus de l\u2019AFP publi\u00e9s sur ce site, et en les utilisant, le cas \u00e9ch\u00e9ant, vous acceptez d'\u00eatre li\u00e9 par les conditions g\u00e9n\u00e9rales d'utilisation susmentionn\u00e9es. L\u2019utilisation de contenus de l'AFP se fait sous votre seule et enti\u00e8re responsabilit\u00e9.","source":"https:\/\/factuel.afp.com\/doc.afp.com.683V363","fact_checker":"https:\/\/belux.wpengine.com\/wp-content\/uploads\/2021\/12\/afp_logo.png","share_this_post_to_edmo_website":false,"affiliation":"BELUX","type":"\u00c9v\u00e9nement ferm\u00e9","location":"","start_date":"","start_date_event_begins_at":"","start_date_event_ends_at":"","end_date":"","end_date_event_begins_at":"","end_date_event_ends_at":"","organizer":"","fact_checker_logo_image":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Attention, ces images d&#039;\u00c9gyptiens lan\u00e7ant des bouteilles remplies de vivres vers Gaza ont \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9es par IA - EDMO Belux<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Attention, ces images d&#039;\u00c9gyptiens lan\u00e7ant des bouteilles remplies de vivres vers Gaza ont \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9es par IA - EDMO Belux\" \/>\n<meta property=\"og:description\" content=\"D\u00e9but mars 2025, Isra\u00ebl a impos\u00e9 \u00e0 Gaza un blocus qui a entra\u00een\u00e9 de tr\u00e8s graves p\u00e9nuries alimentaires, selon l&#039;ONU et des ONG, parmi ses plus de deux millions d&#039;habitants. Le terme de &quot;famine&quot; a officiellement \u00e9t\u00e9 act\u00e9 le 29 juillet par l&#039;IPC, organisation sp\u00e9cialis\u00e9e soutenue par l&#039;ONU. Dans ce contexte, des images sont diffus\u00e9es par des internautes affirmant qu&#039;elles montrent des \u00c9gyptiens jetant \u00e0 la mer des bouteilles remplies de riz, de farine ou de lait en direction de Gaza, en signe de solidarit\u00e9. Mais si cette initiative a bien exist\u00e9, les photos en question ne sont pas authentiques et ont \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9es par intelligence artificielle.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/\" \/>\n<meta property=\"og:site_name\" content=\"EDMO Belux\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-31T09:32:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-31T14:04:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/belux-edmo.s3-accelerate.amazonaws.com\/wp-content\/uploads\/2025\/07\/0ff734c2bd66f95f797ee14a939c63beaeef9b84-ipad.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"master\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Edmo_Belux\" \/>\n<meta name=\"twitter:site\" content=\"@Edmo_Belux\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"master\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/\"},\"author\":{\"name\":\"master\",\"@id\":\"https:\/\/belux.edmo.eu\/#\/schema\/person\/dbe3b252258537fd318f9b5645a30342\"},\"headline\":\"Attention, ces images d&rsquo;\u00c9gyptiens lan\u00e7ant des bouteilles remplies de vivres vers Gaza ont \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9es par IA\",\"datePublished\":\"2025-07-31T09:32:39+00:00\",\"dateModified\":\"2025-07-31T14:04:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/\"},\"wordCount\":1345,\"publisher\":{\"@id\":\"https:\/\/belux.edmo.eu\/#organization\"},\"image\":{\"@id\":\"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/belux-edmo.s3-accelerate.amazonaws.com\/wp-content\/uploads\/2025\/07\/0ff734c2bd66f95f797ee14a939c63beaeef9b84-ipad.jpg\",\"articleSection\":[\"Editor's Choice Slider FR\",\"Fact-Check\",\"Moyen-Orient\",\"Politique\",\"Societe\",\"Technologie\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/\",\"url\":\"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/\",\"name\":\"Attention, ces images d'\u00c9gyptiens lan\u00e7ant des bouteilles remplies de vivres vers Gaza ont \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9es par IA - EDMO Belux\",\"isPartOf\":{\"@id\":\"https:\/\/belux.edmo.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/belux-edmo.s3-accelerate.amazonaws.com\/wp-content\/uploads\/2025\/07\/0ff734c2bd66f95f797ee14a939c63beaeef9b84-ipad.jpg\",\"datePublished\":\"2025-07-31T09:32:39+00:00\",\"dateModified\":\"2025-07-31T14:04:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/#primaryimage\",\"url\":\"https:\/\/belux-edmo.s3-accelerate.amazonaws.com\/wp-content\/uploads\/2025\/07\/0ff734c2bd66f95f797ee14a939c63beaeef9b84-ipad.jpg\",\"contentUrl\":\"https:\/\/belux-edmo.s3-accelerate.amazonaws.com\/wp-content\/uploads\/2025\/07\/0ff734c2bd66f95f797ee14a939c63beaeef9b84-ipad.jpg\",\"width\":1080,\"height\":540,\"caption\":\"Attention, ces images d'\u00c9gyptiens lan\u00e7ant des bouteilles remplies de vivres vers Gaza ont \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9es par IA - Featured image\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/belux.edmo.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Attention, ces images d&#8217;\u00c9gyptiens lan\u00e7ant des bouteilles remplies de vivres vers Gaza ont \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9es par IA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/belux.edmo.eu\/#website\",\"url\":\"https:\/\/belux.edmo.eu\/\",\"name\":\"EDMO Belux\",\"description\":\"Monitoring Disinformation in Belgium and Luxembourg\",\"publisher\":{\"@id\":\"https:\/\/belux.edmo.eu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/belux.edmo.eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/belux.edmo.eu\/#organization\",\"name\":\"EDMO Belux\",\"url\":\"https:\/\/belux.edmo.eu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/belux.edmo.eu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/belux.edmo.eu\/wp-content\/uploads\/2021\/12\/belux-logo-full-color-rgb.svg\",\"contentUrl\":\"https:\/\/belux.edmo.eu\/wp-content\/uploads\/2021\/12\/belux-logo-full-color-rgb.svg\",\"width\":1,\"height\":1,\"caption\":\"EDMO Belux\"},\"image\":{\"@id\":\"https:\/\/belux.edmo.eu\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/Edmo_Belux\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/belux.edmo.eu\/#\/schema\/person\/dbe3b252258537fd318f9b5645a30342\",\"name\":\"master\",\"sameAs\":[\"https:\/\/belux.wpengine.com\"],\"url\":\"https:\/\/belux.edmo.eu\/fr\/author\/master\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Attention, ces images d'\u00c9gyptiens lan\u00e7ant des bouteilles remplies de vivres vers Gaza ont \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9es par IA - EDMO Belux","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/","og_locale":"fr_FR","og_type":"article","og_title":"Attention, ces images d'\u00c9gyptiens lan\u00e7ant des bouteilles remplies de vivres vers Gaza ont \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9es par IA - EDMO Belux","og_description":"D\u00e9but mars 2025, Isra\u00ebl a impos\u00e9 \u00e0 Gaza un blocus qui a entra\u00een\u00e9 de tr\u00e8s graves p\u00e9nuries alimentaires, selon l'ONU et des ONG, parmi ses plus de deux millions d'habitants. Le terme de \"famine\" a officiellement \u00e9t\u00e9 act\u00e9 le 29 juillet par l'IPC, organisation sp\u00e9cialis\u00e9e soutenue par l'ONU. Dans ce contexte, des images sont diffus\u00e9es par des internautes affirmant qu'elles montrent des \u00c9gyptiens jetant \u00e0 la mer des bouteilles remplies de riz, de farine ou de lait en direction de Gaza, en signe de solidarit\u00e9. Mais si cette initiative a bien exist\u00e9, les photos en question ne sont pas authentiques et ont \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9es par intelligence artificielle.\u00a0","og_url":"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/","og_site_name":"EDMO Belux","article_published_time":"2025-07-31T09:32:39+00:00","article_modified_time":"2025-07-31T14:04:56+00:00","og_image":[{"width":1080,"height":540,"url":"https:\/\/belux-edmo.s3-accelerate.amazonaws.com\/wp-content\/uploads\/2025\/07\/0ff734c2bd66f95f797ee14a939c63beaeef9b84-ipad.jpg","type":"image\/jpeg"}],"author":"master","twitter_card":"summary_large_image","twitter_creator":"@Edmo_Belux","twitter_site":"@Edmo_Belux","twitter_misc":{"\u00c9crit par":"master","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/#article","isPartOf":{"@id":"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/"},"author":{"name":"master","@id":"https:\/\/belux.edmo.eu\/#\/schema\/person\/dbe3b252258537fd318f9b5645a30342"},"headline":"Attention, ces images d&rsquo;\u00c9gyptiens lan\u00e7ant des bouteilles remplies de vivres vers Gaza ont \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9es par IA","datePublished":"2025-07-31T09:32:39+00:00","dateModified":"2025-07-31T14:04:56+00:00","mainEntityOfPage":{"@id":"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/"},"wordCount":1345,"publisher":{"@id":"https:\/\/belux.edmo.eu\/#organization"},"image":{"@id":"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/#primaryimage"},"thumbnailUrl":"https:\/\/belux-edmo.s3-accelerate.amazonaws.com\/wp-content\/uploads\/2025\/07\/0ff734c2bd66f95f797ee14a939c63beaeef9b84-ipad.jpg","articleSection":["Editor's Choice Slider FR","Fact-Check","Moyen-Orient","Politique","Societe","Technologie"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/","url":"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/","name":"Attention, ces images d'\u00c9gyptiens lan\u00e7ant des bouteilles remplies de vivres vers Gaza ont \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9es par IA - EDMO Belux","isPartOf":{"@id":"https:\/\/belux.edmo.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/#primaryimage"},"image":{"@id":"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/#primaryimage"},"thumbnailUrl":"https:\/\/belux-edmo.s3-accelerate.amazonaws.com\/wp-content\/uploads\/2025\/07\/0ff734c2bd66f95f797ee14a939c63beaeef9b84-ipad.jpg","datePublished":"2025-07-31T09:32:39+00:00","dateModified":"2025-07-31T14:04:56+00:00","breadcrumb":{"@id":"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/#primaryimage","url":"https:\/\/belux-edmo.s3-accelerate.amazonaws.com\/wp-content\/uploads\/2025\/07\/0ff734c2bd66f95f797ee14a939c63beaeef9b84-ipad.jpg","contentUrl":"https:\/\/belux-edmo.s3-accelerate.amazonaws.com\/wp-content\/uploads\/2025\/07\/0ff734c2bd66f95f797ee14a939c63beaeef9b84-ipad.jpg","width":1080,"height":540,"caption":"Attention, ces images d'\u00c9gyptiens lan\u00e7ant des bouteilles remplies de vivres vers Gaza ont \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9es par IA - Featured image"},{"@type":"BreadcrumbList","@id":"https:\/\/belux.edmo.eu\/fr\/attention-ces-images-dgyptiens-lanant-des-bouteilles-remplies-de-vivres-vers-gaza-ont-t-gnres-par-ia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/belux.edmo.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Attention, ces images d&#8217;\u00c9gyptiens lan\u00e7ant des bouteilles remplies de vivres vers Gaza ont \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9es par IA"}]},{"@type":"WebSite","@id":"https:\/\/belux.edmo.eu\/#website","url":"https:\/\/belux.edmo.eu\/","name":"EDMO Belux","description":"Monitoring Disinformation in Belgium and Luxembourg","publisher":{"@id":"https:\/\/belux.edmo.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/belux.edmo.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/belux.edmo.eu\/#organization","name":"EDMO Belux","url":"https:\/\/belux.edmo.eu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/belux.edmo.eu\/#\/schema\/logo\/image\/","url":"https:\/\/belux.edmo.eu\/wp-content\/uploads\/2021\/12\/belux-logo-full-color-rgb.svg","contentUrl":"https:\/\/belux.edmo.eu\/wp-content\/uploads\/2021\/12\/belux-logo-full-color-rgb.svg","width":1,"height":1,"caption":"EDMO Belux"},"image":{"@id":"https:\/\/belux.edmo.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Edmo_Belux"]},{"@type":"Person","@id":"https:\/\/belux.edmo.eu\/#\/schema\/person\/dbe3b252258537fd318f9b5645a30342","name":"master","sameAs":["https:\/\/belux.wpengine.com"],"url":"https:\/\/belux.edmo.eu\/fr\/author\/master\/"}]}},"menu_order":0,"_links":{"self":[{"href":"https:\/\/belux.edmo.eu\/fr\/wp-json\/wp\/v2\/posts\/399354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/belux.edmo.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/belux.edmo.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/belux.edmo.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/belux.edmo.eu\/fr\/wp-json\/wp\/v2\/comments?post=399354"}],"version-history":[{"count":0,"href":"https:\/\/belux.edmo.eu\/fr\/wp-json\/wp\/v2\/posts\/399354\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/belux.edmo.eu\/fr\/wp-json\/wp\/v2\/media\/399329"}],"wp:attachment":[{"href":"https:\/\/belux.edmo.eu\/fr\/wp-json\/wp\/v2\/media?parent=399354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/belux.edmo.eu\/fr\/wp-json\/wp\/v2\/categories?post=399354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/belux.edmo.eu\/fr\/wp-json\/wp\/v2\/tags?post=399354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}